{"id":2663,"date":"2021-03-09T17:50:40","date_gmt":"2021-03-09T17:50:40","guid":{"rendered":"https:\/\/www.medicina.ufmg.br\/observaped\/?p=2663"},"modified":"2021-03-09T18:36:14","modified_gmt":"2021-03-09T18:36:14","slug":"depressao","status":"publish","type":"post","link":"https:\/\/www.medicina.ufmg.br\/observaped\/depressao\/","title":{"rendered":"Depress\u00e3o"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.medicina.ufmg.br\/observaped\/wp-content\/uploads\/sites\/37\/2021\/03\/Depress\u00e3o.jpg\" alt=\"\" class=\"wp-image-2664\" width=\"396\" height=\"223\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dados sobre <a href=\"https:\/\/www.medicina.ufmg.br\/observaped\/suicidio-na-infancia-e-adolescencia\/\">suic\u00eddio<\/a> mostram o aumento da depress\u00e3o entre as crian\u00e7as e adolescentes, e revelam o aparecimento em idades cada vez mais jovens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 muito importante que os cuidadores fiquem alerta a sinais como: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>sentimento de culpa ou baixa autoestima; <\/li><li> dist\u00farbios do sono (sonol\u00eancia excessiva, <a href=\"https:\/\/www.medicina.ufmg.br\/observaped\/insonia\/\">ins\u00f4nia<\/a> e despertar precoce); <\/li><li> tristeza persistente; <\/li><li> desinteresse pelas atividades habituais e por brincadeiras; <\/li><li> irritabilidade\/agressividade; <\/li><li> dificuldade de concentra\u00e7\u00e3o; <\/li><li> altera\u00e7\u00f5es do apetite; <\/li><li> pensamentos suicidas.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nas crian\u00e7as menores de 12 anos podem estar presentes sintomas como dor abdominal, dor de cabe\u00e7a (cefaleia), n\u00e1useas, dores em membros inferiores, choro f\u00e1cil, comportamento de roer unhas ou morder l\u00e1pis, baixa intera\u00e7\u00e3o verbal, tique, recusa em ir \u00e0 escola, dificuldades escolares e comportamento opositor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na suspeita de depress\u00e3o na inf\u00e2ncia \u00e9 importante procurar um profissional de sa\u00fade para realizar o diagn\u00f3stico precoce e acompanhamento cl\u00ednico.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os principais fatores de risco para a depress\u00e3o na inf\u00e2ncia s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>problemas emocionais durante a gesta\u00e7\u00e3o;<\/li><li> hist\u00f3ria familiar de depress\u00e3o ou transtornos psiqui\u00e1tricos; <\/li><li> <a href=\"https:\/\/www.medicina.ufmg.br\/observaped\/estresse-toxico\/\">estresse t\u00f3xico<\/a> na inf\u00e2ncia, excesso de cobran\u00e7a, <em><a href=\"https:\/\/www.medicina.ufmg.br\/observaped\/bullying\/\">bullying<\/a><\/em>; <\/li><li> <a href=\"https:\/\/www.medicina.ufmg.br\/observaped\/violencia-contra-a-crianca-e-o-adolescente\/\">viol\u00eancia contra a crian\u00e7a <\/a>; <\/li><li> exposi\u00e7\u00e3o excessiva \u00e0s <a href=\"https:\/\/www.medicina.ufmg.br\/observaped\/tempo-de-tela\/\">telas<\/a> (como televis\u00e3o, tablets e celulares);<\/li><li> exposi\u00e7\u00e3o a conte\u00fados inadequados ou violentos; <\/li><li> priva\u00e7\u00e3o cr\u00f4nica de sono; <\/li><li> redu\u00e7\u00e3o do tempo de presen\u00e7a dos pais com a crian\u00e7a;<\/li><li> pouca conviv\u00eancia com outras crian\u00e7as;<\/li><li> pouco tempo ao ar livre e brincadeiras na natureza.  <\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Promover um ambiente de conv\u00edvio afetuoso e equilibrado, onde as crian\u00e7as possam brincar e desenvolver todas as suas potencialidades, \u00e9 fundamental para preven\u00e7\u00e3o e tratamento da depress\u00e3o.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dados sobre suic\u00eddio mostram o aumento da depress\u00e3o entre as crian\u00e7as e adolescentes, e revelam o aparecimento em idades cada&#8230;<\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,12],"tags":[],"class_list":["post-2663","post","type-post","status-publish","format-standard","hentry","category-c25-d","category-pediatria-de-a-a-z"],"_links":{"self":[{"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/posts\/2663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/comments?post=2663"}],"version-history":[{"count":2,"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/posts\/2663\/revisions"}],"predecessor-version":[{"id":2672,"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/posts\/2663\/revisions\/2672"}],"wp:attachment":[{"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/media?parent=2663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/categories?post=2663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medicina.ufmg.br\/observaped\/wp-json\/wp\/v2\/tags?post=2663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}