{"id":3089,"date":"2024-04-16T11:55:51","date_gmt":"2024-04-16T14:55:51","guid":{"rendered":"https:\/\/www.medicina.ufmg.br\/sismid\/?p=3089"},"modified":"2024-04-16T11:55:51","modified_gmt":"2024-04-16T14:55:51","slug":"caracterizacao-dos-aspectos-neuropsicologicos-e-fisiologicos-da-dependencia-de-smartphone","status":"publish","type":"post","link":"https:\/\/www.medicina.ufmg.br\/sismid\/2024\/04\/16\/caracterizacao-dos-aspectos-neuropsicologicos-e-fisiologicos-da-dependencia-de-smartphone\/","title":{"rendered":"Caracteriza\u00e7\u00e3o dos aspectos neuropsicol\u00f3gicos e fisiol\u00f3gicos da depend\u00eancia de smartphone"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A depend\u00eancia de smartphone (DS) tem causado consequ\u00eancias negativas na sociedade atual, mas ainda n\u00e3o foi reconhecida como uma doen\u00e7a, o que dificulta o diagn\u00f3stico e o tratamento dos indiv\u00edduos afetados. O reconhecimento dos fatores associados, das caracter\u00edsticas neuropsicol\u00f3gicas e das caracter\u00edsticas fisiol\u00f3gicas pode constituir evidencia emp\u00edrica da validade do constructo como um transtorno. A DS foi associada ao fato de ser estudante, sexo feminino, idade jovem, renda familiar alta, alta impulsividade, baixo autocontrole e dificuldade de adiar recompensas. Ainda n\u00e3o foram estudados os fatores associados \u00e0 DS na popula\u00e7\u00e3o brasileira e n\u00e3o foi pesquisada a associa\u00e7\u00e3o entre a DS, a satisfa\u00e7\u00e3o com o suporte social e a qualidade de vida, fatores esses que impactam a funcionalidade e podem contribuir para a diferencia\u00e7\u00e3o entre o uso funcional e a depend\u00eancia de smartphone. Estudos pr\u00e9vios tamb\u00e9m demonstraram que os indiv\u00edduos com as s\u00edndromes de depend\u00eancias j\u00e1 reconhecidas como doen\u00e7as apresentam um vi\u00e9s no processo de tomada de decis\u00e3o, pois preferem escolhas vantajosas a curto prazo, mesmo que gerem preju\u00edzos a longo prazo. Esse vi\u00e9s pode contribuir para o in\u00edcio e para a manuten\u00e7\u00e3o das depend\u00eancias, mas ele ainda n\u00e3o foi analisado na DS. Objetivos: analisar os fatores associados \u00e0 DS em estudantes universit\u00e1rios e na popula\u00e7\u00e3o geral; avaliar o processo de tomada de decis\u00e3o sob risco e sob ambiguidade na DS e mensurar os par\u00e2metros fisiol\u00f3gicos durante os testes de tomada de decis\u00e3o.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/repositorio.ufmg.br\/bitstream\/1843\/BUBD-AXVHFG\/1\/tese_julia_machado_khoury_final_01_03_18.pdf\" style=\"background-color:#1a5491\">Acessar<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A depend\u00eancia de smartphone (DS) tem causado consequ\u00eancias negativas na sociedade atual, mas ainda n\u00e3o foi reconhecida como uma doen\u00e7a, o que dificulta o diagn\u00f3stico e o tratamento dos indiv\u00edduos afetados. O reconhecimento dos fatores associados, das caracter\u00edsticas neuropsicol\u00f3gicas e das caracter\u00edsticas fisiol\u00f3gicas pode constituir evidencia emp\u00edrica da validade do constructo como um transtorno. A [&hellip;]<\/p>\n","protected":false},"author":111,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[210,209,212,211],"class_list":["post-3089","post","type-post","status-publish","format-standard","hentry","category-ciencia","tag-celular","tag-dependencia","tag-neuropsicologia","tag-smartphone","entry"],"_links":{"self":[{"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/posts\/3089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/comments?post=3089"}],"version-history":[{"count":1,"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/posts\/3089\/revisions"}],"predecessor-version":[{"id":3090,"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/posts\/3089\/revisions\/3090"}],"wp:attachment":[{"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/media?parent=3089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/categories?post=3089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medicina.ufmg.br\/sismid\/wp-json\/wp\/v2\/tags?post=3089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}